{"id":1588,"date":"2025-05-31T13:31:02","date_gmt":"2025-05-31T13:31:02","guid":{"rendered":"https:\/\/whenua.at\/?page_id=1588"},"modified":"2025-05-31T13:40:12","modified_gmt":"2025-05-31T13:40:12","slug":"die-geschiche","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/die-geschiche\/","title":{"rendered":"Die Geschiche"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8220;.vc_custom_1748698630986{margin-top: -10rem !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner width=&#8220;1\/4&#8243;]<div id=\"sc_title_1168883533\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_shadow\">die Vorgeschischte<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_shadow\">Whenua<\/h2><\/div><!-- \/.sc_title -->[\/vc_column_inner][vc_column_inner width=&#8220;3\/4&#8243;][vc_column_text css=&#8220;&#8220;]<strong>Am Anfang waren die Tore\u2026<\/strong><br \/>\n\u2026 und ihre Erbauer. Noch immer ist unbekannt, welches Volk die Portale aus dem unbekannten Metall erbaute und warum sie es urspr\u00fcnglich taten. Fest steht, dass man durch diese Tore praktisch \u00fcberall hin reisen kann, an jeden Ort, auf jede Ebene und wenn man m\u00e4chtig genug ist sogar durch die Zeit.<\/p>\n<p>Man wei\u00df wenig dar\u00fcber, was mit den Erbauern geschah. Fest steht, dass sie vor sehr langer Zeit verschwanden \u2013 entweder starb das ganze Volk aus, oder vielleicht verlie\u00dfen sie Whenua auch durch die Tore, welche sie selbst erschaffen hatten; bisher vermag das niemand zu sagen. Ihre einzige Hinterlassenschaft sind die Tore selbst und die vielen Fragen, die bis heute unbeantwortet geblieben sind.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8220;&#8220;]Nach den Erbauern siedelten sich verschiedene V\u00f6lker und Lebewesen in Whenua an. Sie kamen aus fremden L\u00e4ndern oder gar durch die Tore, und manche dieser Besiedelungen haben sogar stumme Zeugen hinterlassen \u2013 verfallene Kultst\u00e4tten und H\u00e4user, mitunter sogar ganze St\u00e4dte, die der Wald wieder \u00fcberwuchert hat. Geblieben ist nur ein einziges Volk: die Rwang.<\/p>\n<p>Zu guter Letzt kamen die Eroberer aus dem Norden; \u00fcber das verbrannte Land reisten sie nach Whenua. Sie kamen nicht mit Heerz\u00fcgen oder Kriegsmaschinerie; eher wie ein schleichendes Gift, das sich langsam durch den K\u00f6rper bis zum Herzen frisst. Sie siedelten sich im Norden an und breiteten sich nach S\u00fcden aus. Wo sie begannen, den Boden zu bebauen, musste der Wald weichen und wo sie ihre St\u00e4dte errichteten, da formten sie die Natur nach ihrem Wunsch. Sie brachten ihre Kultur und ihre Br\u00e4uche und vertrieben die Rwang.<\/p>\n<p>So ist das heutige Whenua also eine bunte Mischung aus zwei v\u00f6llig unterschiedlichen Kulturen: die Rwang auf der einen Seite und die \u201eWhenuer\u201c auf der anderen.<\/p>\n<p><strong>Whenua divisa est in partes quartes<\/strong><br \/>\nDie Eroberer, die aus dem Norden kamen um Whenua zu besiedeln, verlie\u00dfen ein Land, das bereits eine Hochkultur hervorgebracht hatte. In diesem Imperium waren die Spielregeln, die Grenzen und auch die Besitzverh\u00e4ltnisse bereits fest verankert und wer arm und gew\u00f6hnlich geboren wurde hatte kaum Chancen, in der Hierarchie hinauf zu klettern. Das Grenzland zwischen dem Mutterland und Whenua war abgewirtschaftet und ausgelaugt \u2013 deswegen wurde (und wird) es auch das \u201everbrannte Land\u201c genannt.<br \/>\nAls der Imperator sein Volk ermunterte, in den S\u00fcden zu reisen und dort neues Land zu besiedeln, war dies ein Schachzug, um von politischen Reibereien im eigenen Land abzulenken. Au\u00dferdem war es eine willkommene Gelegenheit, rivalisierende Adelsfamilien mit den neuen Besitzt\u00fcmern zu belehnen und somit unsch\u00e4dlich zu machen.<br \/>\nDer Plan ging im Wesentlichen auf. Vieles von dem, was im Mutterland als \u201eGesindel\u201c betrachtet wurde, ging nach Whenua und stellte nun kein Problem mehr dar. Die Besiedelung schien zwar m\u00fchsam, doch von Erfolg gekr\u00f6nt, und das brachte der Herrscherfamilie Ansehen im eigenen Land. Lediglich die Steuereinnahmen und Rohstofflieferungen blieben unter den Erwartungen und auch der generelle Kontakt war m\u00fchsam, da es die tote Zone des verbrannten Landes zu \u00fcberbr\u00fccken galt.<br \/>\nSo erlangte Whenua schleichend seine Autonomie. Obwohl es offiziell immer noch eine Kolonie des Mutterlandes ist, besteht der einzige Kontakt zu diesem Reich nur noch durch die Lex Arcana. Es werden keine Steuern und keine Rohstoffe mehr dorthin geschickt und keiner interessiert sich f\u00fcr die politische Lage des anderen.<\/p>\n<p>Whenua selbst wird durch eine Art Feudalsystem verwaltet. Man unterscheidet zwischen Volk und Adel (auch Patrizier genannt). Das Land ist unterteilt in vier Quarter. Dreien davon steht ein Protector vor und einem der Lordprotector, der gleichzeitig das nominale Oberhaupt von ganz Whenua ist. Die Gesetzgebung ist einheitlich; jeder Protector ist der oberste Richter in seinem Quarter. Zudem hat jedes Quarter sein eigenes, stehendes Heer \u2013 zwar sind diese allesamt nicht sehr gro\u00df, doch daf\u00fcr besteht auch keine Notwendigkeit. Im Kriegsfalle erh\u00e4lt der Lordprotector automatisch den Oberbefehl \u00fcber alle Heere und au\u00dferdem wird aus jeder Familie wenigstens eine wehrf\u00e4hige Person zu den Waffen berufen. Die Whenuer sind im Grunde ein sehr freidenkendes, friedliebendes und opportunistisches V\u00f6lkchen. Es gibt keine landesbeherrschende Religion, lediglich den Prinzipien des Schicksals, der Zeit und des Todes wird allerorten Respekt entgegen gebracht. Ansonsten herrscht ziemliche Religionsfreiheit \u2013 solange nicht Menschen geopfert oder H\u00f6llend\u00e4monen angebetet werden\u2026<br \/>\nIm Grunde gelten in Whenua M\u00e4nner und Frauen gleich viel. Im t\u00e4glichen Leben, im Beruf und im Heer, wird kaum ein Unterschied zwischen Mann und Frau gemacht. Einzig die Patrizierfamilien haben ihren Titel lange Zeit nur \u00fcber die m\u00e4nnliche Linie weitervererbt. Erst seit dem Jahr 216 a.P. (Realzeit 2016) k\u00f6nnen auch weibliche Nachkommen den Namen der Adelslinie offiziell erben.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8220;.vc_custom_1748698630986{margin-top: -10rem !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner width=&#8220;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8220;3\/4&#8243;][vc_column_text css=&#8220;&#8220;]Am Anfang waren die Tore\u2026 \u2026 und ihre Erbauer. Noch immer ist unbekannt, welches Volk die Portale aus dem unbekannten Metall erbaute und warum&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1588","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=1588"}],"version-history":[{"count":13,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1588\/revisions"}],"predecessor-version":[{"id":1602,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1588\/revisions\/1602"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=1588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}