{"id":1991,"date":"2025-06-02T14:35:11","date_gmt":"2025-06-02T12:35:11","guid":{"rendered":"https:\/\/whenua.at\/?page_id=1991"},"modified":"2025-06-02T15:15:40","modified_gmt":"2025-06-02T13:15:40","slug":"terranova","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/anglaender\/terranova\/","title":{"rendered":"Terra Nova"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1748870143111{margin-top: -10rem !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;]<div id=\"sc_title_1449616946\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_left sc_item_title_style_shadow\">das Land<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_left sc_item_title_style_shadow\">Terra Nova<\/h2><\/div><!-- \/.sc_title -->[\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1992&#8243; img_size=&#8220;250&#215;250&#8243; alignment=&#8220;center&#8220; style=&#8220;vc_box_shadow_border_circle&#8220; onclick=&#8220;custom_link&#8220; css=&#8220;&#8220; link=&#8220;https:\/\/whenua.at\/wp-content\/uploads\/2025\/06\/Whenua2023_lowres_legas-scaled-1.jpg&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text css=&#8220;&#8220;]Bis zum Jahr 214 a.P. (reale Zeitrechnung 2014) gab es im s\u00fcdwesten Whenuas eine Halbinsel, besiedelt von Menschen, Elfen, Zwergen und anderen Gestalten. Regiert durch eine K\u00f6nigin war das Land ein gesch\u00e4tzter Nachbar von Whenua.<\/p>\n<p>Dann legte sich ein seltsamer Nebel \u00fcber die Halbinsel und es war nicht mehr m\u00f6glich, sie zu betreten. In Whenua waren zu diesem Zeitpunkt alle zu sehr mit den eigenen Problemen besch\u00e4ftigt um sich dar\u00fcber den Kopf zu zerbrechen. Daher wurde einfach abgewartet.<br \/>\nIm Jahr 217 a.P. (reale Zeitrechnung 2017) lichteten sich die Nebel wieder und gaben den Zutritt zu einer v\u00f6llig ver\u00e4nderten Landschaft frei. Was auch immer sich fr\u00fcher auf der Halbinsel befunden hatte war verschwunden und es war nicht m\u00f6glich herauszufinden, wohin oder warum.<\/p>\n<p>Stattdessen wurden Expeditionen gestartet um dieses neue Land zu erforschen.<br \/>\nErste Berichte sprechen von weitl\u00e4ufigen Gebirgen, tiefen W\u00e4ldern und einer v\u00f6llig neuartigen Pflanzen- und Tierwelt, der man mit Vorsicht begegnen sollte.<br \/>\nSeit dem Jahr 218 a.P. fassen nun die ersten Menschen und Elfen zaghaft Fu\u00df in diesem neuen, fremden Land, dessen Geschichtsschreibung somit auch gerade erst beginnt.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_single_image image=&#8220;1780&#8243; img_size=&#8220;125&#215;125&#8243; alignment=&#8220;right&#8220; style=&#8220;vc_box_border&#8220; onclick=&#8220;img_link_large&#8220; css=&#8220;&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1748870143111{margin-top: -10rem !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1992&#8243; img_size=&#8220;250&#215;250&#8243; alignment=&#8220;center&#8220; style=&#8220;vc_box_shadow_border_circle&#8220; onclick=&#8220;custom_link&#8220; css=&#8220;&#8220; link=&#8220;https:\/\/whenua.at\/wp-content\/uploads\/2025\/06\/Whenua2023_lowres_legas-scaled-1.jpg&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text css=&#8220;&#8220;]Bis zum Jahr 214 a.P. (reale Zeitrechnung 2014) gab es im s\u00fcdwesten Whenuas eine&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1980,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1991","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=1991"}],"version-history":[{"count":2,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1991\/revisions"}],"predecessor-version":[{"id":2039,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1991\/revisions\/2039"}],"up":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1980"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}