{"id":2087,"date":"2025-06-02T16:24:30","date_gmt":"2025-06-02T14:24:30","guid":{"rendered":"https:\/\/whenua.at\/?page_id=2087"},"modified":"2025-06-02T17:00:37","modified_gmt":"2025-06-02T15:00:37","slug":"meltus","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/hintergrund-informationen\/religionen\/meltus\/","title":{"rendered":"Meltus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1748876310339{margin-top: -10rem !important;margin-bottom: -8rem !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner]<div id=\"sc_title_1088358147\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_shadow\">Meltus<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_shadow\">Meltus<\/h2><\/div><!-- \/.sc_title -->[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<blockquote><p><strong>MELTUS&#8216; SEGEN MIT DIR, WANDERER DURCH DIE WELTEN<br \/>\n<\/strong>Sei recht herzlich willkommen, Neueinsteiger oder Interessierter, zu einem kurzen \u00dcberblick \u00fcber den Orden von Meltus. Wie du sicher schon geh\u00f6rt hast, spielen wir einen Lichtorden, der in Whenua beheimatet ist, den Lehren des Gottes Meltus folgt und den dunklen M\u00e4chten im Live-Rollenspiel den Kampf angesagt hat.<br \/>\nInnerhalb dieses Rahmens hast du vielf\u00e4ltige M\u00f6glichkeiten, dem Licht zum Sieg zu verhelfen: Ob als strahlender Paladin, weiser Priester, tapferer Ordensritter oder gelehrter Forscher &#8211; jeder Weg f\u00fchrt dich zu spannenden Abenteuern im Kampf gegen das unausweichliche B\u00f6se.<br \/>\nDa wir zahlreiche erfahrene Spieler in unseren Reihen haben, bieten wir f\u00fcr jede Erfahrungsstufe maximalen Spielspa\u00df. Egal ob du erst seit kurzem den Ruf des Lichts vernimmst oder schon viele Schlachten f\u00fcr Meltus geschlagen hast &#8211; bei uns findest du deinen Platz im ewigen Kampf zwischen Licht und Finsternis.<\/p><\/blockquote>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1780&#8243; img_size=&#8220;250&#215;250&#8243; alignment=&#8220;center&#8220; style=&#8220;vc_box_shadow_border_circle&#8220; onclick=&#8220;img_link_large&#8220; css=&#8220;&#8220;][\/vc_column_inner][\/vc_row_inner][vc_separator style=&#8220;shadow&#8220; border_width=&#8220;3&#8243; css=&#8220;&#8220;][vc_single_image image=&#8220;2092&#8243; img_size=&#8220;450&#8243; alignment=&#8220;center&#8220; onclick=&#8220;img_link_large&#8220; css=&#8220;&#8220;][vc_separator style=&#8220;shadow&#8220; border_width=&#8220;3&#8243; css=&#8220;&#8220;][vc_column_text css=&#8220;&#8220;]<strong>ENTSTEHUNGSGESCHICHTE DES ORDENS VON MELTUS<\/strong><\/p>\n<p class=\"ds-markdown-paragraph\">Vor etwa 400 Jahren stie\u00df ein gewisser <strong>Timeus der Reine<\/strong>\u00a0bei seinen Nachforschungen \u00fcber die alten G\u00f6tter auf die Aufzeichnungen eines uralten Gottes namens\u00a0<strong>Meltus<\/strong>. Dieser war geboren worden, als Licht und Dunkelheit erschaffen wurden \u2013 das reine Gegenst\u00fcck zur Finsternis, bestimmt, sie zur\u00fcckzudr\u00e4ngen.<br \/>\nIn diesen Schriften war von einem uralten Tempel die Rede, einem heiligen Ort, den Meltus selbst erschaffen hatte. Dort, so hie\u00df es, ruhte Meltus verborgen, bis die\u00a0<strong>Mehrheit<\/strong> der Sterblichen seine Hilfe ben\u00f6tigen w\u00fcrde. Timeus wusste, dass die Zeit zum Handeln gekommen war, denn dunkle Vorzeichen k\u00fcndigten ein gro\u00dfes \u00dcbel an, das bald \u00fcber die Welt hereinbrechen sollte. So machte er sich mit einer kleinen Schar von Anh\u00e4ngern auf, diesen Tempel zu suchen.\u00a0Ihre Reise f\u00fchrte sie tief in die Berge s\u00fcdlich des heutigen Ostarium. Nach wochenlangem Irren, als sie schon an einen Abbruch der Mission dachten, erschien Timeus ein Zeichen &#8211; Ein <strong>Lichtstrahl<\/strong> vom Himmel wies ihnen den Weg zu einem verborgenen Pfad, der sie fast bis zum Gipfel des h\u00f6chsten Berges f\u00fchrte. Dort fanden sie ein riesiges Tal, in dessen Mitte ein Geb\u00e4ude stand \u2013 ein Tempel, der so hell strahlte, dass er selbst in der Dunkelheit das ganze Tal taghell erleuchtete. Vorsichtig betraten sie das Heiligtum und irrten durch G\u00e4nge und R\u00e4ume, geblendet vom glei\u00dfenden Licht.<br \/>\nSchlie\u00dflich gelangten sie ins innerste Heiligtum. Dort ruhte Meltus selbst in einem gl\u00e4sernen Sarkophag. Als Timeus seine Hand darauf legte, durchstr\u00f6mte ihn eine\u00a0<strong>unfassbare Macht<\/strong>. Der Geist Meltus&#8216; erf\u00fcllte ihn und zeigte ihm den Ursprung aller Dinge sowie die Zukunft. So wurde Timeus zum\u00a0<strong>Auserw\u00e4hlten<\/strong>, zum Propheten Meltus&#8216; \u2013 ausgestattet mit beinahe g\u00f6ttlicher Macht, bis ein Nachfolger seinen Platz einnehmen w\u00fcrde.<\/p>\n<p class=\"ds-markdown-paragraph\">Nach seiner R\u00fcckkehr in die Hauptstadt sammelte Timeus Anh\u00e4nger um sich, und der <strong>Orden von Meltus<\/strong> wurde geboren. Der erste \u2013 und sp\u00e4tere Haupttempel \u2013 entstand in einer Stadt an der das heutigen Vitorino steht. Ein meisterhaftes, golden schimmerndes Bauwerk, das hoch \u00fcber die D\u00e4cher der Stadt aufragte.<br \/>\nDer heilige Tempel in den s\u00fcdlichen Bergen jedoch blieb fortan unauffindbar. Nur der jeweilige Prophet, hei\u00dft es, k\u00f6nnte den Zugang wiederfinden.<br \/>\nSo verbreitete sich der Glaube an Meltus, und in ganz Whenua entstanden Tempel \u2013 als\u00a0<strong>Bollwerk gegen die Dunkelheit<\/strong>\u00a0und als St\u00fctze f\u00fcr die\u00a0<strong>Bewohner Whenuas<\/strong>.<\/p>\n<p>[\/vc_column_text][vc_separator style=&#8220;shadow&#8220; border_width=&#8220;3&#8243; css=&#8220;&#8220;][vc_column_text css=&#8220;&#8220;]<strong>DER ORDENSKODEX<\/strong><\/p>\n<p class=\"ds-markdown-paragraph\">Der\u00a0<strong>Bruderschaft Meltus<\/strong>\u00a0obliegt es, sich um die\u00a0<strong>Reinheit in allen Dingen<\/strong>\u00a0zu k\u00fcmmern:<\/p>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Die Reinheit des K\u00f6rpers<\/strong>\u00a0\u2013 gef\u00e4hrdet durch Krankheiten oder die widernat\u00fcrliche Wiederbelebung durch Nekromanten.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Die Reinheit des Geistes<\/strong>\u00a0\u2013 noch gewichtiger, denn eine Verwirrung des Gem\u00fcts muss bereinigt werden. Hierunter fallen Schwarzmagier, die willentlich ihren und fremden Geist gef\u00e4hrden. Doch die Kinder Meltus unterhalten au\u00dferhalb Ostariums ein Asyl f\u00fcr Opfer geistiger Schw\u00e4che.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Die Reinheit der Seele<\/strong>\u00a0\u2013 die schlimmste Form der Unreinheit, die sich in D\u00e4monen und Geistern manifestiert und vollkommene L\u00e4uterung verlangt.<\/p>\n<\/li>\n<\/ol>\n<p class=\"ds-markdown-paragraph\">Dies sind die hehren Aufgaben der Kinder Meltus.<\/p>\n<p><strong>Verhaltensregeln der Meltus-Anh\u00e4nger:<\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\">Zucht und Anstand<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Einhaltung selbst auferlegter Regeln<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Unbestechlichkeit<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Bescheidenheit<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Unerbittlicher Kampf gegen dunkle Magie<\/p>\n<\/li>\n<\/ul>\n<p><strong>Weltliche Gerichtsbarkeit:<\/strong><\/p>\n<p class=\"ds-markdown-paragraph\">Sollte der lokale Herrscher ein Gl\u00e4ubiger Meltus sein, obliegt der Bruderschaft zus\u00e4tzlich die\u00a0<strong>weltliche Rechtsprechung<\/strong>. Jeder Patrizia kann um die Hilfe eines <strong>Inquisitors der Bruderschaft<\/strong>\u00a0ersuchen \u2013 diese muss zwar nicht gew\u00e4hrt werden, doch meist wird der Bitte entsprochen.<\/p>\n<p class=\"ds-markdown-paragraph\">Wird ein Kind Meltus eines Verbrechens beschuldigt, untersteht es ausschlie\u00dflich der\u00a0<strong>Inquisitionsgerichtsbarkeit<\/strong>. Die Bruderschaft bestraft Vergehen gegen Meltus oder weltliche Gesetze innerhalb ihrer Reihen mit angemessenen Strafen.<\/p>\n<p><strong>Magische Praxis:<\/strong><\/p>\n<p class=\"ds-markdown-paragraph\">Der Bruderschaft sind zwar alle\u00a0<strong>Zauberspr\u00fcche der Magier<\/strong>\u00a0bekannt, doch nur verdiente Mitglieder d\u00fcrfen auf bestimmte Spr\u00fcche zugreifen.<\/p>\n<p><strong>Die unerbittlichen Feinde:<\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\">Anh\u00e4nger dunkler G\u00f6tter<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Schwarzmagie in jeder Form<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Nekromantie<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Blutmagie und verwandte Riten<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Vampirismus<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Untote<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">D\u00e4monische M\u00e4chte und ihr Wirken<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\">Lichtscheues Gesindel und Wesen finsterer Gesinnung<\/p>\n<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_separator style=&#8220;shadow&#8220; border_width=&#8220;3&#8243; css=&#8220;&#8220;][vc_column_text css=&#8220;&#8220;]<strong>Die Ordens Aspekte<\/strong><\/p>\n<ul>\n<li>Haupt-Aspekt: Licht, Ordnung und Reinheit<\/li>\n<li>Priester: Wahrheit und Gerechtigkeit<\/li>\n<li>Kleriker: Gro\u00dfmut und St\u00e4rke<\/li>\n<li>Gelehrte: Weisheit und Erleuchtung<\/li>\n<li>Heiler: Heilung und Leben<br \/>\n<strong>Anmerkung:<\/strong> Grunds\u00e4tzlich vertreten aber alle Kasten gleicherma\u00dfen diese f\u00fcr den Orden so fundamentalen wichtigen Aspekte!<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_separator style=&#8220;shadow&#8220; border_width=&#8220;3&#8243; css=&#8220;&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1748876310339{margin-top: -10rem !important;margin-bottom: -8rem !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;] MELTUS&#8216; SEGEN MIT DIR, WANDERER DURCH DIE WELTEN Sei recht herzlich willkommen, Neueinsteiger oder Interessierter, zu einem kurzen \u00dcberblick&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1921,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2087","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=2087"}],"version-history":[{"count":11,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2087\/revisions"}],"predecessor-version":[{"id":2100,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2087\/revisions\/2100"}],"up":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1921"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=2087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}