{"id":2222,"date":"2025-08-27T12:50:57","date_gmt":"2025-08-27T10:50:57","guid":{"rendered":"https:\/\/whenua.at\/?page_id=2222"},"modified":"2025-08-27T15:46:49","modified_gmt":"2025-08-27T13:46:49","slug":"die-ostarische-fluechtlingssiedlung","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/die-4-quarter\/melvis-2\/die-ostarische-fluechtlingssiedlung\/","title":{"rendered":"Die ostarische Fl\u00fcchtlingssiedlung"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756302408101{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column]<div id=\"sc_title_1232029229\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_left sc_item_title_style_shadow\">DIE<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_left sc_item_title_style_shadow\">ostarische Fl\u00fcchtlingssiedlung<\/h2><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<p data-start=\"174\" data-end=\"520\">Um der Zerst\u00f6rung ihrer Stadt zu entgehen, flohen viele Bewohner Ostariums entlang der S\u00fcdstra\u00dfe nach Norden. In der Angst vor den Gefahren an der Grenze zu den Verbrannten Landen und im Glauben, Schutz durch das nahe Kastell am Rwangreservat zu finden, lie\u00dfen sie sich am Rand des Trutzwaldes nieder \u2013 direkt an dem Weg, der in den Wald f\u00fchrt.<\/p>\n<p data-start=\"522\" data-end=\"698\">Was zun\u00e4chst als Fl\u00fcchtlingszeltstadt begann, wandelt sich nach und nach in eine feste Siedlung. Erste Holzh\u00e4user ersetzen die Zelte, und ein Gef\u00fchl von Best\u00e4ndigkeit w\u00e4chst.<\/p>\n<p data-start=\"700\" data-end=\"852\">Zum Schutz der Gefl\u00fcchteten stellte der Lordprotektor eine Legion ab, die in einem eigens errichteten Milit\u00e4rlager neben der Siedlung stationiert ist.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_wp_custommenu title=&#8220;Melvis&#8220; nav_menu=&#8220;72&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756302408101{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;] Um der Zerst\u00f6rung ihrer Stadt zu entgehen, flohen viele Bewohner Ostariums entlang der S\u00fcdstra\u00dfe nach Norden. In der Angst vor den&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":1688,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2222","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=2222"}],"version-history":[{"count":4,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2222\/revisions"}],"predecessor-version":[{"id":2362,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2222\/revisions\/2362"}],"up":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1688"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=2222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}