{"id":2228,"date":"2025-08-27T12:53:19","date_gmt":"2025-08-27T10:53:19","guid":{"rendered":"https:\/\/whenua.at\/?page_id=2228"},"modified":"2025-08-27T15:46:08","modified_gmt":"2025-08-27T13:46:08","slug":"die-cerulfaelle-cataracta-multiplex-viele-faelle","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/die-4-quarter\/melvis-2\/die-cerulfaelle-cataracta-multiplex-viele-faelle\/","title":{"rendered":"Die Cerulf\u00e4lle \u2013 cataracta multiplex (\u201eviele F\u00e4lle\u201c)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756302366894{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column]<div id=\"sc_title_1973933187\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_left sc_item_title_style_shadow\">DIE<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_left sc_item_title_style_shadow\">Cerulf\u00e4lle<\/h2><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<p data-start=\"223\" data-end=\"243\"><em data-start=\"223\" data-end=\"241\">Rwang horoi tapu<\/em><\/p>\n<p data-start=\"245\" data-end=\"668\">\u201eDas unglaubliche Tosen der vielen kleinen Wasserf\u00e4lle des gro\u00dfen Flusses in der Bucht des Hochlandes f\u00fchrte uns schon von Weitem in diese Richtung. Doch konnten wir allein daraus die Sch\u00f6nheit dieses Ortes nicht erahnen, die sich aus den vielen kleinen Flussstr\u00e4ngen ergab, die sich hier nach unten ergossen. Mehrere, teils \u00fcbereinanderliegende Regenb\u00f6gen blendeten unsere durch die Gischt ohnehin schon getr\u00fcbte Sicht.\u201c<\/p>\n<p data-start=\"670\" data-end=\"794\">So beschrieb ein Legion\u00e4r in seinem Expeditionsbericht die <em data-start=\"729\" data-end=\"750\">cataracta multiplex<\/em>, die gemeinhin Cerulf\u00e4lle genannt werden.<\/p>\n<p data-start=\"796\" data-end=\"1192\">Heute hat sich die Aussicht deutlich ver\u00e4ndert. Zwar sind die Wasserf\u00e4lle immer noch beeindruckend, doch wurden viele der kleineren Str\u00f6me in Holzleitungen gefasst, um die am Fu\u00dfe der Klippen liegende Ortschaft mit Wasser zu versorgen. Zahlreiche Wasserr\u00e4der wurden direkt an den F\u00e4llen errichtet, um die Flaschenz\u00fcge der Kr\u00e4ne anzutreiben, die Waren und Personen hinauf- und hinunterbef\u00f6rdern.<\/p>\n<p data-start=\"1194\" data-end=\"1484\">Gleichzeitig st\u00fcrzen beinahe ununterbrochen Baumst\u00e4mme die F\u00e4lle hinab. Unten, in der kleinen Stadt <em data-start=\"1294\" data-end=\"1308\">Casa Stiptis<\/em> (\u201eStammfall\u201c), werden sie zu Brettern und Bauholz verarbeitet \u2013 ein Bild von Macht und Gesch\u00e4ftigkeit, das die einst reine Natur in eine Quelle des Fortschritts verwandelte.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_wp_custommenu title=&#8220;Melvis&#8220; nav_menu=&#8220;72&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756302366894{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;] Rwang horoi tapu \u201eDas unglaubliche Tosen der vielen kleinen Wasserf\u00e4lle des gro\u00dfen Flusses in der Bucht des Hochlandes f\u00fchrte uns schon&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":1688,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2228","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=2228"}],"version-history":[{"count":5,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2228\/revisions"}],"predecessor-version":[{"id":2360,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2228\/revisions\/2360"}],"up":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1688"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=2228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}