{"id":2320,"date":"2025-08-27T15:02:26","date_gmt":"2025-08-27T13:02:26","guid":{"rendered":"https:\/\/whenua.at\/?page_id=2320"},"modified":"2026-07-03T20:23:49","modified_gmt":"2026-07-03T18:23:49","slug":"inselnredis","status":"publish","type":"page","link":"https:\/\/whenua.at\/index.php\/die-4-quarter\/redis-2\/inselnredis\/","title":{"rendered":"Die Inseln vor Redis"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756301175729{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column]<div id=\"sc_title_917891876\"\n\t\tclass=\"sc_title sc_title_default\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_shadow\">DIE<\/h6><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_shadow\">Inseln vor Redis<\/h2><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<p data-start=\"219\" data-end=\"235\"><strong>Isla Verna<\/strong><\/p>\n<p data-start=\"237\" data-end=\"507\">Vor der K\u00fcste Whenuas liegt die Insel Isla Verna, die sich durch ihre Vielfalt an Landschaften und Siedlungen auszeichnet. Vom mond\u00e4nen Sommerhafen der Patrizier \u00fcber touristische Fischerd\u00f6rfer bis hin zu unber\u00fchrten Palmenw\u00e4ldern bietet die Insel zahlreiche Facetten.<\/p>\n<p data-start=\"514\" data-end=\"532\"><strong>Port Miracul<\/strong><\/p>\n<p data-start=\"534\" data-end=\"940\">Port Miracul ist weniger eine Stadt als vielmehr ein gemeinsamer Hafen f\u00fcr die Schiffe der Reichen. Viele Patrizier und Geldadelige haben im Hinterland der Insel ihre Sommerresidenzen errichtet und nutzen Port Miracul als exklusiven Anlegeplatz. Durch seine gesch\u00fctzte Lage, nah an der K\u00fcste und doch vom Festland abgeschnitten, entwickelte sich die Insel zu einem beliebten R\u00fcckzugsort der Wohlhabenden.<\/p>\n<p data-start=\"947\" data-end=\"966\"><strong>Gro\u00df Waterton<\/strong><\/p>\n<p data-start=\"968\" data-end=\"1260\">Die Entdeckung eines hei\u00dfen Geysirs nahe der Ortschaft machte das kleine Fischerdorf Gro\u00df Waterton rasch zu einer Touristenattraktion. Anders als in Port Miracul zieht der Ort nicht nur die Oberschicht an, sondern wird gleicherma\u00dfen von einfachen Leuten wie auch vom gehobenen Volk besucht.<\/p>\n<p data-start=\"1262\" data-end=\"1526\">Trotz des aufbl\u00fchenden Fremdenverkehrs hat der Ort seinen Ursprung nicht verleugnet: Der Fischfang wurde nie aufgegeben. Besonders die Fischrestaurants von Gro\u00df Waterton sind weithin bekannt \u2013 hier kommen die Meeresfr\u00fcchte beinahe direkt vom Fang auf den Teller.<\/p>\n<p data-start=\"1533\" data-end=\"1549\"><strong>Isla Minor<\/strong><\/p>\n<p data-start=\"1551\" data-end=\"1770\">Die kleine Isla Minor ist gr\u00f6\u00dftenteils unbewohnt, da das felsige Inland von dichtem Palmenwuchs gepr\u00e4gt ist. Nur wenige Rwrang leben hier in bescheidenen Pfahlbauten, und einige Muschelfarmen nutzen die K\u00fcstengew\u00e4sser.<\/p>\n<p data-start=\"1777\" data-end=\"1793\"><strong>Isla Palma<\/strong><\/p>\n<p data-start=\"1795\" data-end=\"2021\">Isla Palma ist fast vollst\u00e4ndig von einem riesigen Palmenwald \u00fcberzogen, der nur am Ufer Platz f\u00fcr breite, goldene Sandstr\u00e4nde l\u00e4sst. Diese einzigartige Landschaft machte die Insel zu einem der beliebtesten Badeorte Whenuas.<\/p>\n<p data-start=\"2028\" data-end=\"2048\"><strong>Port \u00dcbersonne<\/strong><\/p>\n<p data-start=\"2050\" data-end=\"2286\">Die einzige Siedlung auf Isla Palma ist Port \u00dcbersonne. Da die K\u00fcsten vollst\u00e4ndig aus Sand bestehen, errichtete man zun\u00e4chst ein steinernes Fundament, auf dem die gr\u00f6\u00dferen Geb\u00e4ude stehen: ein Rathaus, zwei Gasth\u00e4user und ein Speicher.<\/p>\n<p data-start=\"2288\" data-end=\"2627\">Daneben gibt es einen gro\u00dfz\u00fcgigen Hafen, der auch Schiffe aus \u00dcbersee aufnehmen kann. Alle weiteren Geb\u00e4ude sind Holzpfahlbauten, die direkt im Sand errichtet wurden und durch Stege miteinander verbunden sind. So schmiegt sich Port \u00dcbersonne harmonisch in das Bild der Insel, w\u00e4hrend es gleichzeitig die zahlreichen Badeg\u00e4ste beherbergt.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_wp_custommenu title=&#8220;Redis&#8220; nav_menu=&#8220;74&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1756301175729{margin-top: -140px !important;background-image: url(https:\/\/whenua.at\/wp-content\/uploads\/2025\/05\/bg_white.png?id=1425) !important;}&#8220;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;] Isla Verna Vor der K\u00fcste Whenuas liegt die Insel Isla Verna, die sich durch ihre Vielfalt an Landschaften und Siedlungen auszeichnet.&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":1693,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2320","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/comments?post=2320"}],"version-history":[{"count":6,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2320\/revisions"}],"predecessor-version":[{"id":2490,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/2320\/revisions\/2490"}],"up":[{"embeddable":true,"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/pages\/1693"}],"wp:attachment":[{"href":"https:\/\/whenua.at\/index.php\/wp-json\/wp\/v2\/media?parent=2320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}